{"id":8881,"date":"2025-05-06T11:07:27","date_gmt":"2025-05-06T09:07:27","guid":{"rendered":"https:\/\/ombresetfacettes.com\/?post_type=product&#038;p=8881"},"modified":"2025-05-12T10:40:00","modified_gmt":"2025-05-12T08:40:00","slug":"chandelier-windsor-42","status":"publish","type":"product","link":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/","title":{"rendered":"CHANDELIER WINDSOR-42"},"content":{"rendered":"<p>A forty-two-light gilt-bronze chandelier, richly chased throughout with foliage, scrolls and flowerheads. The branches, which break into several foliate candlearms, are attached to a central hub crowned by a tapered section, and ogee arches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Material: bronze <br \/>Photo finish: gold 24K <br \/>Light arms: 42 <br \/>Dimensions: H 199 x D 150 cm \/ H 78,3 x D 59,1&#8243;<\/p>\n","protected":false},"featured_media":8955,"template":"","meta":[],"product_brand":[],"product_cat":[175],"product_tag":[166],"class_list":["post-8881","product","type-product","status-publish","has-post-thumbnail","product_cat-chandeliers","product_tag-xix-en","pa_taille-140-cm","pa_taille-140-cm-en","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHANDELIER WINDSOR-42 - Ombres et Facettes -<\/title>\n<meta name=\"description\" content=\"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHANDELIER WINDSOR-42 - Ombres et Facettes -\" \/>\n<meta property=\"og:description\" content=\"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/\" \/>\n<meta property=\"og:site_name\" content=\"Ombres et Facettes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T08:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2025\/05\/LUS-WIN-H199-42-site-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/\",\"name\":\"CHANDELIER WINDSOR-42 - Ombres et Facettes -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LUS-WIN-H199-42-site-scaled.jpg\",\"datePublished\":\"2025-05-06T09:07:27+00:00\",\"dateModified\":\"2025-05-12T08:40:00+00:00\",\"description\":\"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LUS-WIN-H199-42-site-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LUS-WIN-H199-42-site-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Lustre Windsor 42 bras - Chandelier Windsor 42 arms\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/chandelier-windsor-42\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHANDELIER WINDSOR-42\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#website\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/\",\"name\":\"Ombres et Facettes\",\"description\":\"Ombres & Facettes - French chandlery\",\"publisher\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ombresetfacettes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#organization\",\"name\":\"Ombres et Facettes\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png\",\"contentUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png\",\"width\":1299,\"height\":414,\"caption\":\"Ombres et Facettes\"},\"image\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ombres.et.facettes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHANDELIER WINDSOR-42 - Ombres et Facettes -","description":"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/","og_locale":"en_US","og_type":"article","og_title":"CHANDELIER WINDSOR-42 - Ombres et Facettes -","og_description":"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","og_url":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/","og_site_name":"Ombres et Facettes","article_modified_time":"2025-05-12T08:40:00+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2025\/05\/LUS-WIN-H199-42-site-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/","url":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/","name":"CHANDELIER WINDSOR-42 - Ombres et Facettes -","isPartOf":{"@id":"https:\/\/ombresetfacettes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/#primaryimage"},"image":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/#primaryimage"},"thumbnailUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2025\/05\/LUS-WIN-H199-42-site-scaled.jpg","datePublished":"2025-05-06T09:07:27+00:00","dateModified":"2025-05-12T08:40:00+00:00","description":"Discover our CHANDELIER WINDSOR-42 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","breadcrumb":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/#primaryimage","url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2025\/05\/LUS-WIN-H199-42-site-scaled.jpg","contentUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2025\/05\/LUS-WIN-H199-42-site-scaled.jpg","width":2560,"height":2560,"caption":"Lustre Windsor 42 bras - Chandelier Windsor 42 arms"},{"@type":"BreadcrumbList","@id":"https:\/\/ombresetfacettes.com\/en\/produit\/chandelier-windsor-42\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Collection","item":"https:\/\/ombresetfacettes.com\/en\/collection\/"},{"@type":"ListItem","position":2,"name":"CHANDELIER WINDSOR-42"}]},{"@type":"WebSite","@id":"https:\/\/ombresetfacettes.com\/#website","url":"https:\/\/ombresetfacettes.com\/","name":"Ombres et Facettes","description":"Ombres & Facettes - French chandlery","publisher":{"@id":"https:\/\/ombresetfacettes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ombresetfacettes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ombresetfacettes.com\/#organization","name":"Ombres et Facettes","url":"https:\/\/ombresetfacettes.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ombresetfacettes.com\/#\/schema\/logo\/image\/","url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/07\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png","contentUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/07\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png","width":1299,"height":414,"caption":"Ombres et Facettes"},"image":{"@id":"https:\/\/ombresetfacettes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ombres.et.facettes\/"]}]}},"_links":{"self":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/8881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":5,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/8881\/revisions"}],"predecessor-version":[{"id":8982,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/8881\/revisions\/8982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/media\/8955"}],"wp:attachment":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/media?parent=8881"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_brand?post=8881"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_cat?post=8881"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_tag?post=8881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}