{"id":6927,"date":"2022-10-30T11:39:18","date_gmt":"2022-10-30T09:39:18","guid":{"rendered":"https:\/\/ombresetfacettes.com\/produit\/table-lamp-crystal-1\/"},"modified":"2025-08-21T15:53:47","modified_gmt":"2025-08-21T13:53:47","slug":"lamp-a-poser-crystal-1","status":"publish","type":"product","link":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/","title":{"rendered":"TABLE LAMP LOUIS XV-1"},"content":{"rendered":"<p>Rich bronze and clear crystal light fixture in the Louis XV style. The bronze ends, adorned with leaves, form a sublime setting for the crystal vase.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Material: bronze and clear crystal<br \/>Photo finish: antique bronze<br \/>Light arm: 1<br \/>Dimensions with shade: H 78.5 x D 45 cm \/ H 30.9 x D 17.7&#8243;\u00a0<br \/>Dimensions without shade: H 57 x D 26 cm \/ H 22.4 x D 10.2\u2033 <br \/>Weight : 23 kg<\/p>\n","protected":false},"featured_media":6898,"template":"","meta":[],"product_brand":[],"product_cat":[27,176],"product_tag":[208,166],"class_list":["post-6927","product","type-product","status-publish","has-post-thumbnail","product_cat-divers","product_cat-more","product_tag-xix-siecle","product_tag-xix-en","pa_taille-56-84-cm-en","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TABLE LAMP LOUIS XV-1 - Ombres et Facettes -<\/title>\n<meta name=\"description\" content=\"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TABLE LAMP LOUIS XV-1 - Ombres et Facettes -\" \/>\n<meta property=\"og:description\" content=\"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Ombres et Facettes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T13:53:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/10\/LAMPE-A-POSER-CRISTAL-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/\",\"name\":\"TABLE LAMP LOUIS XV-1 - Ombres et Facettes -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAMPE-A-POSER-CRISTAL-1.jpg\",\"datePublished\":\"2022-10-30T09:39:18+00:00\",\"dateModified\":\"2025-08-21T13:53:47+00:00\",\"description\":\"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAMPE-A-POSER-CRISTAL-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAMPE-A-POSER-CRISTAL-1.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Louis XV bronze & cristal table lamp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/produit\\\/lamp-a-poser-crystal-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/ombresetfacettes.com\\\/en\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TABLE LAMP LOUIS XV-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#website\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/\",\"name\":\"Ombres et Facettes\",\"description\":\"Ombres & Facettes - French chandlery\",\"publisher\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ombresetfacettes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#organization\",\"name\":\"Ombres et Facettes\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png\",\"contentUrl\":\"https:\\\/\\\/ombresetfacettes.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png\",\"width\":1299,\"height\":414,\"caption\":\"Ombres et Facettes\"},\"image\":{\"@id\":\"https:\\\/\\\/ombresetfacettes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ombres.et.facettes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TABLE LAMP LOUIS XV-1 - Ombres et Facettes -","description":"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/","og_locale":"en_US","og_type":"article","og_title":"TABLE LAMP LOUIS XV-1 - Ombres et Facettes -","og_description":"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","og_url":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/","og_site_name":"Ombres et Facettes","article_modified_time":"2025-08-21T13:53:47+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/10\/LAMPE-A-POSER-CRISTAL-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/","url":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/","name":"TABLE LAMP LOUIS XV-1 - Ombres et Facettes -","isPartOf":{"@id":"https:\/\/ombresetfacettes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/#primaryimage"},"image":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/#primaryimage"},"thumbnailUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/10\/LAMPE-A-POSER-CRISTAL-1.jpg","datePublished":"2022-10-30T09:39:18+00:00","dateModified":"2025-08-21T13:53:47+00:00","description":"Discover our TABLE LAMP LOUIS XV-1 as well as our entire collection. We offer a custom service, let us inspire you among our multiple choices of high-end finishes.","breadcrumb":{"@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/#primaryimage","url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/10\/LAMPE-A-POSER-CRISTAL-1.jpg","contentUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/10\/LAMPE-A-POSER-CRISTAL-1.jpg","width":1200,"height":1200,"caption":"Louis XV bronze & cristal table lamp"},{"@type":"BreadcrumbList","@id":"https:\/\/ombresetfacettes.com\/en\/produit\/lamp-a-poser-crystal-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Collection","item":"https:\/\/ombresetfacettes.com\/en\/collection\/"},{"@type":"ListItem","position":2,"name":"TABLE LAMP LOUIS XV-1"}]},{"@type":"WebSite","@id":"https:\/\/ombresetfacettes.com\/#website","url":"https:\/\/ombresetfacettes.com\/","name":"Ombres et Facettes","description":"Ombres & Facettes - French chandlery","publisher":{"@id":"https:\/\/ombresetfacettes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ombresetfacettes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ombresetfacettes.com\/#organization","name":"Ombres et Facettes","url":"https:\/\/ombresetfacettes.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ombresetfacettes.com\/#\/schema\/logo\/image\/","url":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/07\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png","contentUrl":"https:\/\/ombresetfacettes.com\/wp-content\/uploads\/2022\/07\/cropped-OMBRES-ET-FACETTES-LOGO-2018-2-transparent.png","width":1299,"height":414,"caption":"Ombres et Facettes"},"image":{"@id":"https:\/\/ombresetfacettes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ombres.et.facettes\/"]}]}},"_links":{"self":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/6927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/6927\/revisions"}],"predecessor-version":[{"id":10574,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product\/6927\/revisions\/10574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/media\/6898"}],"wp:attachment":[{"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/media?parent=6927"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_brand?post=6927"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_cat?post=6927"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ombresetfacettes.com\/en\/wp-json\/wp\/v2\/product_tag?post=6927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}